{"id":5534,"date":"2016-04-13T13:51:03","date_gmt":"2016-04-13T13:51:03","guid":{"rendered":"https:\/\/megafm.com.uy\/web\/2016\/04\/13\/mega-fm-incorporo-moderna-tecnologia-procesador-de-audio-digital-y-sistema-rds-2\/"},"modified":"2016-04-13T13:51:03","modified_gmt":"2016-04-13T13:51:03","slug":"mega-fm-incorporo-moderna-tecnologia-procesador-de-audio-digital-y-sistema-rds-2","status":"publish","type":"post","link":"https:\/\/megafm.com.uy\/web\/mega-fm-incorporo-moderna-tecnologia-procesador-de-audio-digital-y-sistema-rds-2\/","title":{"rendered":"Mega FM incorporo moderna t\u00e9cnologia, procesador de audio digital y sistema RDS"},"content":{"rendered":"<p><img decoding=\"async\" class=\" size-full wp-image-3224\" src=\"https:\/\/megafm.com.uy\/web\/wp-content\/uploads\/2016\/04\/rdsmega.jpg\" alt=\"\" width=\"350\" srcset=\"https:\/\/megafm.com.uy\/web\/wp-content\/uploads\/2016\/04\/rdsmega.jpg 800w, https:\/\/megafm.com.uy\/web\/wp-content\/uploads\/2016\/04\/rdsmega-300x206.jpg 300w, https:\/\/megafm.com.uy\/web\/wp-content\/uploads\/2016\/04\/rdsmega-768x527.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Mega FM 98.5 anexo moderna tecnolog\u00eda a su emisi\u00f3n. En el marco de un proyecto apoyado por DINATEL, anexamos u procesador de audio digital de \u00faltima generaci\u00f3n lo que permite una alta definici\u00f3n en la calidad de sonido.<\/p>\n<p>Adem\u00e1s estando a la vanguardia tecnol\u00f3gica incorporamos sistema RDS (Radio Data System), los escuchan que cuenten con equipos digitales que soporte esta tecnolog\u00eda podr\u00e1n apreciar diversos textos, anunci\u00f3s, comunicados, informaci\u00f3n de trafico y mucho m\u00e1s.<\/p>\n<p>es un importante avance para un medio comunitario del interior del departamento, el equipo de Mega FM 98.5 agradece a locutores, colaboradores, oyentes, comerciantes, a la ciudad de Vergara y la regi\u00f3n por ser participe de los avances de Mega FM 98.5<\/p>\n<p><!--more--><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega FM 98.5 anexo moderna tecnolog\u00eda a su emisi\u00f3n. En el marco de un proyecto apoyado por DINATEL, anexamos u procesador de audio digital de \u00faltima generaci\u00f3n lo que permite una alta definici\u00f3n en la calidad de sonido. Adem\u00e1s estando a la vanguardia tecnol\u00f3gica incorporamos sistema RDS (Radio Data System), los escuchan que cuenten con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[133],"tags":[],"class_list":["post-5534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos"],"_links":{"self":[{"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/posts\/5534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/comments?post=5534"}],"version-history":[{"count":0,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/posts\/5534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/media\/3224"}],"wp:attachment":[{"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/media?parent=5534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/categories?post=5534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/tags?post=5534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}