{"id":5610,"date":"2012-12-28T07:21:35","date_gmt":"2012-12-28T07:21:35","guid":{"rendered":"https:\/\/megafm.com.uy\/web\/2012\/12\/28\/la-diligencia-vergara-2\/"},"modified":"2012-12-28T07:21:35","modified_gmt":"2012-12-28T07:21:35","slug":"la-diligencia-vergara-2","status":"publish","type":"post","link":"https:\/\/megafm.com.uy\/web\/la-diligencia-vergara-2\/","title":{"rendered":"La diligencia &#8211; Vergara"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3194\" src=\"https:\/\/megafm.com.uy\/web\/wp-content\/uploads\/2012\/12\/diligencia.jpg\" width=\"300\" height=\"185\" alt=\"diligencia\" \/><\/p>\n<p style=\"text-align: left;\">&nbsp;<\/p>\n<p><span style=\"color: #333333; font-family: 'lucida grande', tahoma, verdana, arial, sans-serif; line-height: 14px; text-align: left;\">A QU\u00c9 HORA LLEGA LA DILIGENCIA ?&#8230;.El sub-t\u00edtulo de estas l\u00edneas y la foto en cuesti\u00f3n es parte del acervo hist\u00f3rico del Escribano Jos\u00e9 Luis Cuello.- La foto fue tomada en Vergara, aproximadamente en el a\u00f1o 1906 y se trata de la diligencia de Serapio T\u00e9liz, que un\u00eda Treinta y Tres con Villa Artigas (hoy, ciudad de R\u00edo Branco).- El lugar f\u00edsico de la toma fotogr<span class=\"text_exposed_show\" style=\"display: inline; color: #333333; font-family: 'lucida grande', tahoma, verdana, arial, sans-serif; line-height: 14px; text-align: left;\">\u00e1fica es frente a la Oficina de Correos de Vergara, por calle Dionisio Coronel (edificio que actualmente est\u00e1 remodelado) y ubicado al Noreste de la Plaza Confraternidad.- A la derecha, en primer t\u00e9rmino puede apreciarse la Parroquia del Sant\u00edsimo Sacramento, de Vergara y contiguo a \u00e9sta, la casa que fuera de do\u00f1a Juana Gregoria Gigena Alves de Fabeiro (actualmente familias Est\u00e9vez- Bentancur y Senosia\u00edn- Est\u00e9vez).- Adem\u00e1s se puede divisar nit\u00eddamente la parte superior del altillo perteneciente a dicha casa y que est\u00e1 por calle Jacinto Ruiz (hermanas Est\u00e9vez-Nogueira).- Quienes aparecen en la foto son: Pedro B. da Silva ( de sombrero y guardapolvo blanco- casado con do\u00f1a Fermina Nicacia Gigena Alves); Serapio T\u00e9liz (mayoral y due\u00f1o de la diligencia) y Visitaci\u00f3n Ramos \u00bb El Chiche\u00bb (de pa\u00f1uelo blanco y sombrero), que era el \u00abcuarteador\u00bb de la diligencia y no ten\u00eda 20 a\u00f1os de edad, cumplidos.- Lo del sub-t\u00edtulo al parecer nunca ocurri\u00f3 para don Serapio T\u00e9liz&#8230;.porque seg\u00fan las viejas memorias del pago, era uno de los \u00abguerreros del camino\u00bb, que m\u00e1s se ajustaba a los horarios de salida y llegada&#8230;&#8230; Texto: Jorge Muniz<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A QU\u00c9 HORA LLEGA LA DILIGENCIA ?&#8230;.El sub-t\u00edtulo de estas l\u00edneas y la foto en cuesti\u00f3n es parte del acervo hist\u00f3rico del Escribano Jos\u00e9 Luis Cuello.- La foto fue tomada en Vergara, aproximadamente en el a\u00f1o 1906 y se trata de la diligencia de Serapio T\u00e9liz, que un\u00eda Treinta y Tres con Villa Artigas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3194,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/posts\/5610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/comments?post=5610"}],"version-history":[{"count":0,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/posts\/5610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/media\/3194"}],"wp:attachment":[{"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/media?parent=5610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/categories?post=5610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megafm.com.uy\/web\/wp-json\/wp\/v2\/tags?post=5610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}